{"id":4083,"date":"2023-04-10T22:49:12","date_gmt":"2023-04-11T01:49:12","guid":{"rendered":"https:\/\/www.brafip.org.br\/brafip\/?p=4083"},"modified":"2024-08-23T22:20:24","modified_gmt":"2024-08-24T01:20:24","slug":"llamada-de-ideas-brafip-2023","status":"publish","type":"post","link":"https:\/\/brafip.org.br\/brafip\/2023\/04\/10\/llamada-de-ideas-brafip-2023\/","title":{"rendered":"Webinar de lanzamiento &#8211; Llamada de Ideas BraFip 2023"},"content":{"rendered":"<figure class=\"wp-block-post-featured-image\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1620\" height=\"1620\" src=\"https:\/\/brafip.org.br\/brafip\/wp-content\/uploads\/2023\/04\/CI23-Webinar-de-lanzamiento-ES.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" style=\"object-fit:contain;\" srcset=\"https:\/\/brafip.org.br\/brafip\/wp-content\/uploads\/2023\/04\/CI23-Webinar-de-lanzamiento-ES.png 1620w, https:\/\/brafip.org.br\/brafip\/wp-content\/uploads\/2023\/04\/CI23-Webinar-de-lanzamiento-ES-300x300.png 300w, https:\/\/brafip.org.br\/brafip\/wp-content\/uploads\/2023\/04\/CI23-Webinar-de-lanzamiento-ES-1024x1024.png 1024w, https:\/\/brafip.org.br\/brafip\/wp-content\/uploads\/2023\/04\/CI23-Webinar-de-lanzamiento-ES-150x150.png 150w, https:\/\/brafip.org.br\/brafip\/wp-content\/uploads\/2023\/04\/CI23-Webinar-de-lanzamiento-ES-768x768.png 768w, https:\/\/brafip.org.br\/brafip\/wp-content\/uploads\/2023\/04\/CI23-Webinar-de-lanzamiento-ES-1536x1536.png 1536w, https:\/\/brafip.org.br\/brafip\/wp-content\/uploads\/2023\/04\/CI23-Webinar-de-lanzamiento-ES-70x70.png 70w\" sizes=\"(max-width: 1620px) 100vw, 1620px\" \/><\/figure>\n\n\n<p>Registrar <a href=\"http:\/\/bit.ly\/incoday2023\" target=\"_blank\" rel=\"noreferrer noopener\">AQU\u00cd<\/a><\/p>\n\n\n\n<p>BraFIP, cuya actividad comenz\u00f3 en 2011, fue creada originalmente como la plataforma tecnol\u00f3gica brasile\u00f1a, en la forma definida por la Uni\u00f3n Europea para asistir en el desarrollo tecnol\u00f3gico de los pa\u00edses de Europa del Este.<\/p>\n\n\n\n<p>Desde 2015, BraFIP act\u00faa como una asociaci\u00f3n sin fines de lucro, para asistir en la construcci\u00f3n de proyectos de Investigaci\u00f3n, Desarrollo e Innovaci\u00f3n (I+D+i) en cooperaci\u00f3n, es decir, involucrando varias empresas, universidades y centros de investigaci\u00f3n, ampliando su alcance continuamente.<\/p>\n\n\n\n<p>Desde 2021 cuenta con el respaldo de ALETI &#8211; Federaci\u00f3n Iberoamericana de Entidades Empresariales de Tecnolog\u00edas de la Informaci\u00f3n, y en este a\u00f1o 2023 comenzamos a contar con EscalaLatam.<\/p>\n\n\n\n<p>Para seguir impulsando la formaci\u00f3n de nuevos grupos de empresas, startups, universidades y centros de investigaci\u00f3n, ALETI, BraFIP y EscalaLatam impulsan la Convocatoria de Ideas 2023 para proyectos de I+D+i, la octava convocatoria de esta iniciativa.<\/p>\n\n\n\n<p>Las mejores ideas tendr\u00e1n la oportunidad de ser presentadas durante el D\u00eda de la Cooperaci\u00f3n Internacional (IncoDay), evento previsto para octubre de este a\u00f1o en Panam\u00e1.<\/p>\n\n\n\n<p>La participaci\u00f3n en esta Convocatoria de Ideas est\u00e1 abierta a todas las empresas (buscadores de ideas o proveedores), startups, centros de investigaci\u00f3n e innovaci\u00f3n en un entorno acad\u00e9mico o instituciones cient\u00edficas, siempre que est\u00e9n interesadas en trabajar en formas de acelerar la innovaci\u00f3n tecnol\u00f3gica, independientemente de si pertenezcan o no a entidades adheridas, as\u00ed como para personas jur\u00eddicas que deseen presentar desaf\u00edos.<\/p>\n\n\n\n<p>Nota 1: Esta convocatoria tiene como objetivo identificar oportunidades de cooperaci\u00f3n en Investigaci\u00f3n, Desarrollo e Innovaci\u00f3n, incluyendo ideas, proyectos y productos. Para participar en esta Convocatoria de Ideas, complete el cuestionario a continuaci\u00f3n. El plazo de participaci\u00f3n finaliza el 28 de julio de 2023.<\/p>\n\n\n\n<p>Nota 2: si su organizaci\u00f3n quiere presentar m\u00e1s de una idea, debe completar un cuestionario para cada idea.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Registrar AQU\u00cd BraFIP, cuya actividad comenz\u00f3 en 2011, fue creada originalmente como la plataforma tecnol\u00f3gica brasile\u00f1a, en la forma definida por la Uni\u00f3n Europea para asistir en el desarrollo tecnol\u00f3gico de los pa\u00edses de Europa del Este. Desde 2015, BraFIP act\u00faa como una asociaci\u00f3n sin fines de lucro, para asistir&hellip;<\/p>\n","protected":false},"author":2,"featured_media":4068,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-4083","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/brafip.org.br\/brafip\/wp-json\/wp\/v2\/posts\/4083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brafip.org.br\/brafip\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/brafip.org.br\/brafip\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/brafip.org.br\/brafip\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/brafip.org.br\/brafip\/wp-json\/wp\/v2\/comments?post=4083"}],"version-history":[{"count":9,"href":"https:\/\/brafip.org.br\/brafip\/wp-json\/wp\/v2\/posts\/4083\/revisions"}],"predecessor-version":[{"id":4099,"href":"https:\/\/brafip.org.br\/brafip\/wp-json\/wp\/v2\/posts\/4083\/revisions\/4099"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/brafip.org.br\/brafip\/wp-json\/wp\/v2\/media\/4068"}],"wp:attachment":[{"href":"https:\/\/brafip.org.br\/brafip\/wp-json\/wp\/v2\/media?parent=4083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/brafip.org.br\/brafip\/wp-json\/wp\/v2\/categories?post=4083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/brafip.org.br\/brafip\/wp-json\/wp\/v2\/tags?post=4083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}